{"id":1660,"date":"2016-04-29T11:15:53","date_gmt":"2016-04-29T09:15:53","guid":{"rendered":"http:\/\/www.viverezen.it\/giornale-bio\/?p=1660"},"modified":"2017-02-03T09:27:10","modified_gmt":"2017-02-03T08:27:10","slug":"acqua-che-ti-passa","status":"publish","type":"post","link":"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/","title":{"rendered":"Acqua che ti passa"},"content":{"rendered":"<p>In Giappone la prevenzione passa dall\u2019acqua.<\/p>\n<p>Che l\u2019acqua sia uno degli elementi fondamentali per il nostro benessere, non ci sono mai stati dubbi;\u00a0 in Giappone, per\u00f2, sono convinti che un piccolo accorgimento alle nostre abitudini possa prevenire malattie come mal di testa, problemi cardiaci, artrite, epilessia, sovrappeso, bronchite, asma, tubercolosi, meningite, malattie renali e urinarie, vomito, gastrite, diarrea, emorroidi, diabete, stitichezza, dolori mestruali, malattie alle orecchie, al naso e alla gola.<\/p>\n<p>La Japan Medical Association ha, infatti, approvato la \u201cterapia dell\u2019acqua\u201d, una pratica molto diffusa tra la popolazione, che contribuisce a disintossicare il nostro corpo da scorie e tossine.<\/p>\n<p>Cosa importante, prima di iniziare la terapia, \u00e8 che l\u2019acqua utilizzata dovr\u00e0 essere di qualit\u00e0, quindi priva di calcare, fluoro o altre sostanze chimiche. E\u2019 consigliabile anche bere acqua a temperatura ambiente e non troppo fredda. Volendo si potete aggiungere anche un po\u2019 di succo di limone per rafforzarne gli effetti.<\/p>\n<p>La terapia \u00e8 semplice: subito dopo esservi alzati, bevete quattro bicchieri di acqua prima di lavarvi i denti o di mangiare. Ricordate che dovete bere l\u2019acqua lentamente e fare piccole pause tra un bicchiere e l\u2019altro; evitate di mangiare nei 45 minuti successivi. Dopo colazione, evitate di mangiare per altre 2 ore.<\/p>\n<p>E adesso, due piccole precisazioni: se non vi sentite in grado di iniziare bevendo quattro bicchieri di acqua subito dopo esservi alzati, iniziate con uno o due e poi aumentate fino a raggiungere la quantit\u00e0 consigliata; in alcuni casi si possono presentare sintomi propri della disintossicazione che sono: prurito, vertigini, nausea, mal di testa, mal di stomaco, ansia o diarrea. Tuttavia, sono sintomi normali che si presentano quando il corpo elimina tossine e combatte gli organismi nocivi.<\/p>\n<p>Ah, ovviamente, avrete bisogno del bagno un po\u2019 pi\u00f9 spesso, ma noi lo abbiamo provato e gli effetti sono positivi. Provate anche voi e fateci sapere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Giappone la prevenzione passa dall\u2019acqua. Che l\u2019acqua sia uno degli elementi fondamentali per il nostro benessere, non ci sono mai stati dubbi;\u00a0 in Giappone, per\u00f2, sono convinti che un piccolo accorgimento alle nostre abitudini possa prevenire malattie come mal di testa, problemi cardiaci, artrite, epilessia, sovrappeso, bronchite, asma, tubercolosi, meningite, malattie renali e urinarie, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Acqua che ti passa - Vivere Zen<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Acqua che ti passa - Vivere Zen\" \/>\r\n<meta property=\"og:description\" content=\"In Giappone la prevenzione passa dall\u2019acqua. Che l\u2019acqua sia uno degli elementi fondamentali per il nostro benessere, non ci sono mai stati dubbi;\u00a0 in Giappone, per\u00f2, sono convinti che un piccolo accorgimento alle nostre abitudini possa prevenire malattie come mal di testa, problemi cardiaci, artrite, epilessia, sovrappeso, bronchite, asma, tubercolosi, meningite, malattie renali e urinarie, [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Vivere Zen\" \/>\r\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/VivereZen\/\" \/>\r\n<meta property=\"article:published_time\" content=\"2016-04-29T09:15:53+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2017-02-03T08:27:10+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.viverezen.it\/giornale-bio\/wp-content\/uploads\/2016\/04\/Japanese-Drinking-Water-2.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"290\" \/>\r\n\t<meta property=\"og:image:height\" content=\"313\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Redazione VivereZen\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione VivereZen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/\",\"url\":\"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/\",\"name\":\"Acqua che ti passa - Vivere Zen\",\"isPartOf\":{\"@id\":\"https:\/\/www.viverezen.it\/giornale-bio\/#website\"},\"datePublished\":\"2016-04-29T09:15:53+00:00\",\"dateModified\":\"2017-02-03T08:27:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.viverezen.it\/giornale-bio\/#\/schema\/person\/9617eea4629b49ad5e59f806fe11d2e1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.viverezen.it\/giornale-bio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acqua che ti passa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.viverezen.it\/giornale-bio\/#website\",\"url\":\"https:\/\/www.viverezen.it\/giornale-bio\/\",\"name\":\"Vivere Zen\",\"description\":\"Lo Zen e l&#039;arte di arredare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.viverezen.it\/giornale-bio\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.viverezen.it\/giornale-bio\/#\/schema\/person\/9617eea4629b49ad5e59f806fe11d2e1\",\"name\":\"Redazione VivereZen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.viverezen.it\/giornale-bio\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.viverezen.it\/giornale-bio\/wp-content\/uploads\/2020\/02\/vz-logo-tondo-150x150.jpg\",\"contentUrl\":\"https:\/\/www.viverezen.it\/giornale-bio\/wp-content\/uploads\/2020\/02\/vz-logo-tondo-150x150.jpg\",\"caption\":\"Redazione VivereZen\"},\"description\":\"Manifattura e qualit\u00e0 italiana in stile orientale. Bio Zen per noi significa rispetto dell'intero ciclo di produzione e consumo. Coltivazioni Bio o di provenienza controllata delle materie prime, rispetto del lavoro, economia Italiana, importazione da Circuiti Etici o Verificati, rispetto del risparmio del cliente, no materiali tossici durante la produzione, biodegradabilit\u00e0, tra le nostre linee guida. Vieni a trovarci su Viverezen.it!\",\"sameAs\":[\"http:\/\/www.viverezen.it\",\"https:\/\/www.facebook.com\/VivereZen\/\"],\"url\":\"https:\/\/www.viverezen.it\/giornale-bio\/author\/redazione-viverezen\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acqua che ti passa - Vivere Zen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/","og_locale":"it_IT","og_type":"article","og_title":"Acqua che ti passa - Vivere Zen","og_description":"In Giappone la prevenzione passa dall\u2019acqua. Che l\u2019acqua sia uno degli elementi fondamentali per il nostro benessere, non ci sono mai stati dubbi;\u00a0 in Giappone, per\u00f2, sono convinti che un piccolo accorgimento alle nostre abitudini possa prevenire malattie come mal di testa, problemi cardiaci, artrite, epilessia, sovrappeso, bronchite, asma, tubercolosi, meningite, malattie renali e urinarie, [&hellip;]","og_url":"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/","og_site_name":"Vivere Zen","article_author":"https:\/\/www.facebook.com\/VivereZen\/","article_published_time":"2016-04-29T09:15:53+00:00","article_modified_time":"2017-02-03T08:27:10+00:00","og_image":[{"width":290,"height":313,"url":"https:\/\/www.viverezen.it\/giornale-bio\/wp-content\/uploads\/2016\/04\/Japanese-Drinking-Water-2.jpg","type":"image\/jpeg"}],"author":"Redazione VivereZen","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione VivereZen","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/","url":"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/","name":"Acqua che ti passa - Vivere Zen","isPartOf":{"@id":"https:\/\/www.viverezen.it\/giornale-bio\/#website"},"datePublished":"2016-04-29T09:15:53+00:00","dateModified":"2017-02-03T08:27:10+00:00","author":{"@id":"https:\/\/www.viverezen.it\/giornale-bio\/#\/schema\/person\/9617eea4629b49ad5e59f806fe11d2e1"},"breadcrumb":{"@id":"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.viverezen.it\/giornale-bio\/acqua-che-ti-passa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.viverezen.it\/giornale-bio\/"},{"@type":"ListItem","position":2,"name":"Acqua che ti passa"}]},{"@type":"WebSite","@id":"https:\/\/www.viverezen.it\/giornale-bio\/#website","url":"https:\/\/www.viverezen.it\/giornale-bio\/","name":"Vivere Zen","description":"Lo Zen e l&#039;arte di arredare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.viverezen.it\/giornale-bio\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.viverezen.it\/giornale-bio\/#\/schema\/person\/9617eea4629b49ad5e59f806fe11d2e1","name":"Redazione VivereZen","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.viverezen.it\/giornale-bio\/#\/schema\/person\/image\/","url":"https:\/\/www.viverezen.it\/giornale-bio\/wp-content\/uploads\/2020\/02\/vz-logo-tondo-150x150.jpg","contentUrl":"https:\/\/www.viverezen.it\/giornale-bio\/wp-content\/uploads\/2020\/02\/vz-logo-tondo-150x150.jpg","caption":"Redazione VivereZen"},"description":"Manifattura e qualit\u00e0 italiana in stile orientale. Bio Zen per noi significa rispetto dell'intero ciclo di produzione e consumo. Coltivazioni Bio o di provenienza controllata delle materie prime, rispetto del lavoro, economia Italiana, importazione da Circuiti Etici o Verificati, rispetto del risparmio del cliente, no materiali tossici durante la produzione, biodegradabilit\u00e0, tra le nostre linee guida. Vieni a trovarci su Viverezen.it!","sameAs":["http:\/\/www.viverezen.it","https:\/\/www.facebook.com\/VivereZen\/"],"url":"https:\/\/www.viverezen.it\/giornale-bio\/author\/redazione-viverezen\/"}]}},"_links":{"self":[{"href":"https:\/\/www.viverezen.it\/giornale-bio\/wp-json\/wp\/v2\/posts\/1660"}],"collection":[{"href":"https:\/\/www.viverezen.it\/giornale-bio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.viverezen.it\/giornale-bio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.viverezen.it\/giornale-bio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.viverezen.it\/giornale-bio\/wp-json\/wp\/v2\/comments?post=1660"}],"version-history":[{"count":1,"href":"https:\/\/www.viverezen.it\/giornale-bio\/wp-json\/wp\/v2\/posts\/1660\/revisions"}],"predecessor-version":[{"id":1662,"href":"https:\/\/www.viverezen.it\/giornale-bio\/wp-json\/wp\/v2\/posts\/1660\/revisions\/1662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.viverezen.it\/giornale-bio\/wp-json\/wp\/v2\/media\/1663"}],"wp:attachment":[{"href":"https:\/\/www.viverezen.it\/giornale-bio\/wp-json\/wp\/v2\/media?parent=1660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.viverezen.it\/giornale-bio\/wp-json\/wp\/v2\/categories?post=1660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.viverezen.it\/giornale-bio\/wp-json\/wp\/v2\/tags?post=1660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}